{"id":5556,"date":"2022-03-22T19:23:15","date_gmt":"2022-03-22T18:23:15","guid":{"rendered":"https:\/\/investiga.puenteromano.net\/?p=5556"},"modified":"2022-03-26T17:41:21","modified_gmt":"2022-03-26T16:41:21","slug":"riega-de-collia","status":"publish","type":"post","link":"https:\/\/investiga.puenteromano.net\/index.php\/2022\/03\/22\/riega-de-collia\/","title":{"rendered":"Riega de Coll\u00eda"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"958\" height=\"1280\" data-id=\"5559\" src=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/9F5CF02E-0ADF-4E28-B029-57C9C7D71D8D-edited.jpeg\" alt=\"\" class=\"wp-image-5559\" srcset=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/9F5CF02E-0ADF-4E28-B029-57C9C7D71D8D-edited.jpeg 958w, https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/9F5CF02E-0ADF-4E28-B029-57C9C7D71D8D-edited-480x641.jpeg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 958px, 100vw\" \/><figcaption>Riega de Coll\u00eda, actualmente en sequ\u00eda<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Riega de Coll\u00eda.<\/strong><\/li><li>Localizaci\u00f3n: Coll\u00eda, Parres, Asturias<\/li><li>Estado: en sequ\u00eda<\/li><li>Informaci\u00f3n: experiencia propia<\/li><li>Autor\u00eda de im\u00e1genes y dibujo: Jaime \u00c1lvarez P\u00e9rez<\/li><li>Autor: Jaime \u00c1lvarez P\u00e9rez<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jaime \u00c1lvarez.\u00a0<\/strong><em>La riega de Coll\u00eda<\/em> est\u00e1 situada al este del pueblo, siguiendo un camino constituido por piedras y c\u00e9sped. La riega sol\u00eda albergar m\u00e1s agua, proveniente del monte, y serv\u00eda de riego a campos de pasto para animales y a ciertos cultivos. Tambi\u00e9n serv\u00eda de paso a ganaderos para llevar a animales a los pastos que hab\u00eda un poco m\u00e1s arriba, caminando de poco en poco, debido a lo dificultoso que puede resultar el paso a los animales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el paso del tiempo, la riega fue sec\u00e1ndose y, a su vez, la maleza empez\u00f3 a crecer sobre ella, impidiendo al no ser retirada el paso del agua. Visto el desuso del camino y el poco agua proporcionado por la riega, vecinos de Coll\u00eda decidieron poner una valla en el camino hacia ella para evitar accidentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta riega tiene cierto valor sentimental para mi, debido a que de peque\u00f1o sol\u00eda ir a jugar all\u00ed muy a menudo. Tambi\u00e9n tiene valor por el uso que se le dio durante a\u00f1os por parte de ganaderos como v\u00eda de paso, sin olvidar la funci\u00f3n de riego a los prados y cultivos cercanos.  Este es un peque\u00f1o aviso de que el cambio clim\u00e1tico afecta a los entornos rurales de forma significativa, cambiando sus paisajes y secando las peque\u00f1as reservas de agua.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/6522E1B1-6009-442B-A8BE-D73FB0948C1C-1024x768.jpeg\" alt=\"\" class=\"wp-image-5566\" width=\"405\" height=\"302\"\/><figcaption>Representaci\u00f3n dibujada (basada en memoria) del aspecto de la riega hace a\u00f1os.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Riega de Coll\u00eda. Localizaci\u00f3n: Coll\u00eda, Parres, Asturias Estado: en sequ\u00eda Informaci\u00f3n: experiencia propia Autor\u00eda de im\u00e1genes y dibujo: Jaime \u00c1lvarez P\u00e9rez Autor: Jaime \u00c1lvarez P\u00e9rez Jaime \u00c1lvarez.\u00a0La riega de Coll\u00eda est\u00e1 situada al este del pueblo, siguiendo un camino constituido por piedras y c\u00e9sped. La riega sol\u00eda albergar m\u00e1s agua, proveniente del monte, y serv\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5556","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/5556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/comments?post=5556"}],"version-history":[{"count":2,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/5556\/revisions"}],"predecessor-version":[{"id":5906,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/5556\/revisions\/5906"}],"wp:attachment":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media?parent=5556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/categories?post=5556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/tags?post=5556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}