{"id":4697,"date":"2022-03-16T18:57:06","date_gmt":"2022-03-16T17:57:06","guid":{"rendered":"https:\/\/investiga.puenteromano.net\/?p=4697"},"modified":"2022-03-26T12:47:54","modified_gmt":"2022-03-26T11:47:54","slug":"calero","status":"publish","type":"post","link":"https:\/\/investiga.puenteromano.net\/index.php\/2022\/03\/16\/calero\/","title":{"rendered":"Calero Felm\u00edn, Vegacervera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Filosof\u00eda\/Mar, 13, 2022 \/Hoja de registro<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/b\/bf\/ForndeCal%C3%A7.jpg\/220px-ForndeCal%C3%A7.jpg\" alt=\"\" width=\"315\" height=\"236\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Identificaci\u00f3n: <\/strong>Horno para hacer cal.<\/li><li><strong>Dimensiones:<\/strong> forma cil\u00edndrica; Altura (3,5m)<\/li><li><strong>Temperatura<\/strong>: 850-1000\u00baC.<\/li><li><strong>Construcci\u00f3n:<\/strong> Exterior (ladrillos\/piedra). <\/li><li><strong>Localizaci\u00f3n:<\/strong> Vegacervera, Le\u00f3n,(Calero Felm\u00edn).<\/li><li><strong>Conservaci\u00f3n: <\/strong>no est\u00e1 en uso.<\/li><li><strong>Autor:<\/strong> Jaime Camblor Garc\u00eda.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/th.bing.com\/th\/id\/OIP.no0RD0DmXglzq_j7CsXAAQHaDP?pid=ImgDet&amp;rs=1\" alt=\"Ver las im\u00e1genes de origen\" width=\"663\" height=\"290\" \/><figcaption>Partes del calero.<em> Bing.com<\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"https:\/\/th.bing.com\/th\/id\/R.cc955df7d57c25f36acb861905309232?rik=zCm%2bOxzLX09ERw&amp;riu=http%3a%2f%2fwww.villadeorgaz.es%2fimagenes%2forgaz-horno-cal2.gif&amp;ehk=BoAkd32iYkEvjdzrgj9HGoqcoCIefEckRYbxtf2yUxs%3d&amp;risl=&amp;pid=ImgRaw&amp;r=0\" alt=\"Ver las im\u00e1genes de origen\" \/><figcaption>Organizaci\u00f3n del calero. <em>Blogspot.com<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/image-5.jpeg\" alt=\"\" class=\"wp-image-5866\" width=\"429\" height=\"286\" srcset=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/image-5.jpeg 342w, https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/image-5-300x200.jpeg 300w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><figcaption>Calero de Felm\u00edn. <em>Jaime Camblor Garc\u00eda<\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\"><strong> El <em>calero<\/em><\/strong>, tambi\u00e9n llamado horno de cal, permite la creaci\u00f3n de \u00f3xido de calcio (cal), mediante la calcinaci\u00f3n de piedra caliza. La calcinaci\u00f3n de la piedra caliza se produce a unos 850\u00baC, pero normalmente se usa una temperatura de 1000\u00baC, para una mayor rapidez en la reacci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un horno tradicional de cal es un pozo cil\u00edndrico, cuyas paredes est\u00e1n cubiertas de arcilla para que no se disperse el calor. Debe tener un poyete, donde empezar a poner las piedras calizas y una boca en su parte inferior, desde donde se alimenta el fuego. Por uno de los laterales se excava una rampa, que llega desde la superficie hasta la base del pozo, donde se abre una boca para introducir el combustible. Esta es la zona conocida como \u00abservidor\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ubicaban en territorios donde hab\u00eda piedra caliza y combustible, que sol\u00eda ser le\u00f1a de roble o de encina, o tambi\u00e9n carb\u00f3n, como era en el calero de Felm\u00edn. El carb\u00f3n proced\u00eda de las minas de Matallana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> La piedra la extra\u00eda una cuadrilla de obreros que la llevaban hasta la boca del horno, all\u00ed se rellenaba el horno con la piedra y se avivaba la caldera, durante al menos tres d\u00edas. Se produc\u00eda una combusti\u00f3n lenta y con poco ox\u00edgeno, que calcinaba la piedra, una vez extra\u00eddas del horno, eran machacadas y cribadas hasta obtener la cal. Esta se trasladaba en carros para su venta directa en las obras o se llevaba a los almacenistas para su distribuci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era propiedad del ayuntamiento y se arrendaba a un propietario, quien contrataba a 5 trabajadores de otros concejos de su entorno, para su explotaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cal es un material esencial para la construcci\u00f3n, y tambi\u00e9n un fertilizante que mejora el rendimiento de los cultivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos <em>caleros<\/em> proliferaron en los primeros a\u00f1os del S.XX, y su m\u00e1xima producci\u00f3n coincidi\u00f3 con los a\u00f1os posteriores a la guerra civil. La producci\u00f3n actual de cal tiene lugar en modernas industrias, con las que la fabricaci\u00f3n artesanal no puede competir.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Filosof\u00eda\/Mar, 13, 2022 \/Hoja de registro Identificaci\u00f3n: Horno para hacer cal. Dimensiones: forma cil\u00edndrica; Altura (3,5m) Temperatura: 850-1000\u00baC. Construcci\u00f3n: Exterior (ladrillos\/piedra). Localizaci\u00f3n: Vegacervera, Le\u00f3n,(Calero Felm\u00edn). Conservaci\u00f3n: no est\u00e1 en uso. Autor: Jaime Camblor Garc\u00eda. El calero, tambi\u00e9n llamado horno de cal, permite la creaci\u00f3n de \u00f3xido de calcio (cal), mediante la calcinaci\u00f3n de piedra caliza. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,23,46],"tags":[],"class_list":["post-4697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitectura","category-economia","category-hojas-de-registro"],"_links":{"self":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/comments?post=4697"}],"version-history":[{"count":15,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4697\/revisions"}],"predecessor-version":[{"id":5867,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4697\/revisions\/5867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media\/5840"}],"wp:attachment":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media?parent=4697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/categories?post=4697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/tags?post=4697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}