{"id":4201,"date":"2022-03-20T11:53:27","date_gmt":"2022-03-20T10:53:27","guid":{"rendered":"https:\/\/investiga.puenteromano.net\/?p=4201"},"modified":"2022-03-26T19:28:58","modified_gmt":"2022-03-26T18:28:58","slug":"maestros","status":"publish","type":"post","link":"https:\/\/investiga.puenteromano.net\/index.php\/2022\/03\/20\/maestros\/","title":{"rendered":"Maestros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Poo, h. 1950. Alumnos de las escuelas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arantxa Garc\u00eda Villar<\/strong>. Los alumnos ten\u00edan un respeto riguroso hacia los profesores, puesto que cuando no cumpl\u00edan las normas impuestas eran castigados f\u00edsicamente. Estos no eran tolerantes en ninguno de los sentidos. Cumpl\u00edan sus objetivos a base de que los alumnos aprendieran de memoria unos contenidos, y se transmit\u00edan unos valores de la sociedad muy claros sin dar alternativa a los alumnos para que valorasen y reflexionasen cr\u00edticamente sobre ellos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El maestro y la maestra eran respetados y valorados por una sociedad que ve\u00eda en ellos los valores a seguir. En el pueblo, era el segundo referente intelectual m\u00e1s estimado, despu\u00e9s del cura. Eran un modelo y ejemplo para sus alumnos, inspirado por la relaci\u00f3n entre lo que dec\u00eda y lo que hac\u00eda, entre lo que aplicaba para s\u00ed mismo y para los dem\u00e1s. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer maestro que se recuerda es Don Ceferino, que fue el que m\u00e1s a\u00f1os permaneci\u00f3 en la escuela. Era de Castilla-La Mancha y acab\u00f3 tan enamorado del pueblo que termin\u00f3 por hacerlo tambi\u00e9n de una humilde campesina del vecindario, con la que despu\u00e9s contrajo matrimonio. La segunda se llamaba Mar\u00eda Jes\u00fas y era de Oviedo. Fue la que menos a\u00f1os estuvo y de la que menos recuerdos se tiene. Y la \u00faltima maestra fue Mar\u00eda \u00c1ngeles, que tambi\u00e9n era de Oviedo y es la m\u00e1s recordada. Esta fue la maestra a la que los alumnos le cogieron m\u00e1s cari\u00f1o, pues era un poco m\u00e1s liberal y menos autoritaria, pero nunca le perdieron el respeto y la admiraci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2022\/03\/Profesores-1024x1024.jpg\" alt=\"\" class=\"wp-image-5247\" width=\"169\" height=\"169\"\/><figcaption>Don Ceferino y Mari\u00e1ngeles<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La ense\u00f1anza se apoyaba mucho en la teor\u00eda y poco en la pr\u00e1ctica; y la forma de aprender estaba basada en la repetici\u00f3n.       Los contenidos que se transmit\u00edan eran conceptuales y actitudinales, aunque no se usaban estos nombres para designarlos. El m\u00e9todo que utilizaban surg\u00eda del propio profesor, sin tener en cuenta las variables ni caracter\u00edsticas de los alumnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuentes:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BENA SIERRA, Tomasa (2022). Vecina de Poo, abuela de la autora. 84 a\u00f1os.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/investiga.puenteromano.net\/index.php\/2021\/12\/14\/antiguas-escuelas-de-poo-de-cabrales\/\">Volver a Las Escuelas<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Poo, h. 1950. Alumnos de las escuelas Arantxa Garc\u00eda Villar. Los alumnos ten\u00edan un respeto riguroso hacia los profesores, puesto que cuando no cumpl\u00edan las normas impuestas eran castigados f\u00edsicamente. Estos no eran tolerantes en ninguno de los sentidos. Cumpl\u00edan sus objetivos a base de que los alumnos aprendieran de memoria unos contenidos, y se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[38,47],"tags":[],"class_list":["post-4201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memoria-historica","category-mundo-rural"],"_links":{"self":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/comments?post=4201"}],"version-history":[{"count":11,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4201\/revisions"}],"predecessor-version":[{"id":5932,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/4201\/revisions\/5932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media\/5022"}],"wp:attachment":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media?parent=4201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/categories?post=4201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/tags?post=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}