{"id":1122,"date":"2020-12-16T12:56:53","date_gmt":"2020-12-16T11:56:53","guid":{"rendered":"https:\/\/investiga.puenteromano.net\/?p=1122"},"modified":"2021-01-27T13:04:41","modified_gmt":"2021-01-27T12:04:41","slug":"memorias-de-cain","status":"publish","type":"post","link":"https:\/\/investiga.puenteromano.net\/index.php\/2020\/12\/16\/memorias-de-cain\/","title":{"rendered":"Memorias de Ca\u00edn"},"content":{"rendered":"\n<div class=\"wp-block-cover has-background-dim\" style=\"background-image:url(https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-04-04-at-17.16.22.jpeg)\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h3 class=\"wp-block-heading\">                                                             La ruta del Cares, hace 60 a\u00f1os, no hab\u00eda atracci\u00f3n alguna sino modos de vivir. <\/h3>\n<\/div><\/div>\n\n\n\n<p class=\"has-drop-cap has-primary-color has-background-background-color has-text-color has-background wp-block-paragraph\">Hacer la Ruta del Cares se considera una actividad l\u00fadica m\u00e1s entre el amplio abanico disponible. Pero hace sesenta a\u00f1os caminarla todos los d\u00edas era algo m\u00e1s que rutina. Levantarse a las 5 de la ma\u00f1ana y arrancar en noche cerrada y acompa\u00f1ada de posibles temporales era lo habitual en Ca\u00edn. Hace 60 a\u00f1os el monte no era una fuente de diversi\u00f3n, sino una tierra de vivir. Porque de hoy en d\u00eda vemos de lo m\u00e1s arriesgado iniciar una ruta monta\u00f1osa de estas caracter\u00edsticas con una simple tormenta, pero los vecinos de Ca\u00edn no pod\u00edan detenerse por esto.<\/p>\n\n\n\n<div class=\"wp-block-cover has-background-dim-50 has-primary-background-color has-background-dim\" style=\"background-image:url(https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-04-04-at-17.17.02.jpeg);min-height:297px;aspect-ratio:unset;\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Una Ruta, un pueblo y muchas historias.<\/h2>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La vida en Ca\u00edn no era f\u00e1cil. Cain es un peque\u00f1o pueblo con dos \u00fanicas v\u00edas de comunicaci\u00f3n: La salida por el Cares hacia Poncebos (Asturias) y la vieja carretera a Posada de Valde\u00f3n. Conseguir  productos o \u00fatiles que fueran m\u00e1s all\u00e1 de la subsistencia era costoso, por lo que combinar la ganader\u00eda y agricultura locales con los viajes semanales y el burro en cualquiera de esas dos direcciones era la rutina de la gente de Ca\u00edn.<\/p>\n\n\n\n<div class=\"wp-block-cover has-background-dim\" style=\"background-image:url(https:\/\/investiga.puenteromano.net\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-04-30-at-16.00.26.jpeg);min-height:282px;background-position:51% 61%;aspect-ratio:unset;\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h4 class=\"wp-block-heading\">La historia de una joven Ca\u00edneja.<\/h4>\n<\/div><\/div>\n\n\n\n<p class=\"has-drop-cap has-primary-color has-background-background-color has-text-color has-background wp-block-paragraph\">Fueron muchas las madrugadas con las que esta mujer inici\u00f3 el camino, realizando viajes de ida o de vuelta. Posiblemente lo haya recorrido mas de cientos de veces,&nbsp;actualmente ve la senda como algo inabordable, pero hace m\u00e1s de 60 a\u00f1os se mov\u00eda por ella como pez en el agua. De d\u00eda o de noche, con frio o con altas temperaturas, sola o acompa\u00f1ada de cabras o burros,&nbsp;realiz\u00f3 la ruta en todas las condiciones imaginables. Entre todas ellas&nbsp;recuerda una con especial miedo: Era una tarde de febrero y la tormenta&nbsp;dio paso al anochecer. Ella lo recuerda&nbsp;viviamente, sola junto a una burra en medio de la noche, en alg\u00fan lugar inh\u00f3spito&nbsp;del Cares. No le qued\u00f3  m\u00e1s remedio que hacerse un hueco entre las paredes de la senda y pasar la noche ah\u00ed, junto a la burra, tapada con lo poco que llevaba en el zurr\u00f3n, y esperar a que noche y tormenta dieran paso&nbsp;al amanecer. Hay muchas m\u00e1s historias grabadas en la ruta, y tambi\u00e9n m\u00e1s divertidas&nbsp;pero no que olvidar la dureza y las sombras que tuvo la Ruta del Cares para los vecinos de Ca\u00edn.<\/p>\n\n\n\n<h6 class=\"has-accent-background-color has-text-color has-background wp-block-heading\" style=\"color:#ead8b6\">Con esta historia quiz\u00e1 seamos<br>capaces de asomarnos un poco a  la vida de aquellos a\u00f1os, y<br>recuperar alguno de los secretos<br>que guardan las paredes del Cares.<\/h6>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/investiga.puenteromano.net\/?p=1522&amp;preview=true\">Historias del Cares<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:Informaci\u00f3n e im\u00e1genes obtenidas gracias a la colaboraci\u00f3n de Sadia Perez, Veneranda, abuela del autor (77 a\u00f1os 2020) vecina de Ca\u00edn.                                                                               Autor: Bustillo Campillo, Andy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hacer la Ruta del Cares se considera una actividad l\u00fadica m\u00e1s entre el amplio abanico disponible. Pero hace sesenta a\u00f1os caminarla todos los d\u00edas era algo m\u00e1s que rutina. Levantarse a las 5 de la ma\u00f1ana y arrancar en noche cerrada y acompa\u00f1ada de posibles temporales era lo habitual en Ca\u00edn. Hace 60 a\u00f1os el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1122","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/1122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/comments?post=1122"}],"version-history":[{"count":17,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/1122\/revisions"}],"predecessor-version":[{"id":1591,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/posts\/1122\/revisions\/1591"}],"wp:attachment":[{"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/media?parent=1122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/categories?post=1122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/investiga.puenteromano.net\/index.php\/wp-json\/wp\/v2\/tags?post=1122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}